{"id":60753,"date":"2021-07-15T17:01:27","date_gmt":"2021-07-15T15:01:27","guid":{"rendered":"https:\/\/floresdeloscaminosasantiago.eu\/plant-species\/fagonia-cretica\/"},"modified":"2026-04-23T14:39:26","modified_gmt":"2026-04-23T12:39:26","slug":"fagonia-cretica","status":"publish","type":"plant-species","link":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/","title":{"rendered":"Fagonia cretica"},"featured_media":36457,"parent":0,"template":"","meta":[],"families":[9344],"ecologie":[7287,6417,6383],"flowering-months":[9613],"plant-sizes":[9754],"flower-sizes":[10652],"provinces":[11174],"caminos":[5908],"colors":[5904,5888],"countries":[1123],"class_list":["post-60753","plant-species","type-plant-species","status-publish","has-post-thumbnail","hentry","families-fagonia-nl","ecologie-deserted-fields-nl","ecologie-dry-scrubs-nl","ecologie-stony-soils-nl","flowering-months-3-6-nl","plant-sizes-1-6-dm-nl","flower-sizes-ca-15-18-mm-nl","provinces-alicante-nl","caminos-ruta-de-la-lana","colors-blauw","colors-paars","countries-spain"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fagonia cretica - Flores de los Caminos a Santiago<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fagonia cretica - Flores de los Caminos a Santiago\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/\" \/>\n<meta property=\"og:site_name\" content=\"Flores de los Caminos a Santiago\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T12:39:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Fagonia_cretica-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/\",\"url\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/\",\"name\":\"Fagonia cretica - Flores de los Caminos a Santiago\",\"isPartOf\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Fagonia_cretica-1.jpg\",\"datePublished\":\"2021-07-15T15:01:27+00:00\",\"dateModified\":\"2026-04-23T12:39:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#primaryimage\",\"url\":\"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Fagonia_cretica-1.jpg\",\"contentUrl\":\"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Fagonia_cretica-1.jpg\",\"width\":600,\"height\":337},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plant species\",\"item\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fagonia cretica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/#website\",\"url\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/\",\"name\":\"Flores de los Caminos a Santiago\",\"description\":\"Stimulate the interest in the flora of Spain and Portugal\",\"alternateName\":\"Stimulate the interest in the flora of Spain and Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fagonia cretica - Flores de los Caminos a Santiago","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/","og_locale":"nl_NL","og_type":"article","og_title":"Fagonia cretica - Flores de los Caminos a Santiago","og_url":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/","og_site_name":"Flores de los Caminos a Santiago","article_modified_time":"2026-04-23T12:39:26+00:00","og_image":[{"width":600,"height":337,"url":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Fagonia_cretica-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/","url":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/","name":"Fagonia cretica - Flores de los Caminos a Santiago","isPartOf":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#primaryimage"},"image":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#primaryimage"},"thumbnailUrl":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Fagonia_cretica-1.jpg","datePublished":"2021-07-15T15:01:27+00:00","dateModified":"2026-04-23T12:39:26+00:00","breadcrumb":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#primaryimage","url":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Fagonia_cretica-1.jpg","contentUrl":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Fagonia_cretica-1.jpg","width":600,"height":337},{"@type":"BreadcrumbList","@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/fagonia-cretica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/"},{"@type":"ListItem","position":2,"name":"Plant species","item":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/"},{"@type":"ListItem","position":3,"name":"Fagonia cretica"}]},{"@type":"WebSite","@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/#website","url":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/","name":"Flores de los Caminos a Santiago","description":"Stimulate the interest in the flora of Spain and Portugal","alternateName":"Stimulate the interest in the flora of Spain and Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/plant-species\/60753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/plant-species"}],"about":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/types\/plant-species"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/media\/36457"}],"wp:attachment":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/media?parent=60753"}],"wp:term":[{"taxonomy":"families","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/families?post=60753"},{"taxonomy":"ecologie","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/ecologie?post=60753"},{"taxonomy":"flowering-months","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/flowering-months?post=60753"},{"taxonomy":"plant-sizes","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/plant-sizes?post=60753"},{"taxonomy":"flower-sizes","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/flower-sizes?post=60753"},{"taxonomy":"provinces","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/provinces?post=60753"},{"taxonomy":"caminos","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/caminos?post=60753"},{"taxonomy":"colors","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/colors?post=60753"},{"taxonomy":"countries","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/countries?post=60753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}