{"id":60688,"date":"2021-07-15T17:01:35","date_gmt":"2021-07-15T15:01:35","guid":{"rendered":"https:\/\/floresdeloscaminosasantiago.eu\/plant-species\/glaucium-corniculatum\/"},"modified":"2026-04-23T14:37:07","modified_gmt":"2026-04-23T12:37:07","slug":"glaucium-corniculatum","status":"publish","type":"plant-species","link":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/","title":{"rendered":"Glaucium corniculatum"},"featured_media":37274,"parent":0,"template":"","meta":{"_acf_changed":false},"families":[8146],"ecologie":[6316,6143,8147],"flowering-months":[9609],"plant-sizes":[9995],"flower-sizes":[10349],"provinces":[11151],"caminos":[4647],"colors":[5892,5887],"countries":[1123],"class_list":["post-60688","plant-species","type-plant-species","status-publish","has-post-thumbnail","hentry","families-glaucium-nl","ecologie-borders-of-caminos-nl","ecologie-ruderal-sites-nl","ecologie-sides-of-fields-in-culture-or-fallow-nl","flowering-months-4-7-nl","plant-sizes-3-4-dm-nl","flower-sizes-30-40-mm-nl","provinces-zaragoza-nl","caminos-camino-catalan-montserrat-fuentes-de-ebro","colors-oranje","colors-rood","countries-spain"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Glaucium corniculatum - Flores de los Caminos a Santiago<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glaucium corniculatum - Flores de los Caminos a Santiago\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/\" \/>\n<meta property=\"og:site_name\" content=\"Flores de los Caminos a Santiago\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T12:37:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Glaucium_corniculatum-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/plant-soorten\\\/glaucium-corniculatum\\\/\",\"url\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/plant-soorten\\\/glaucium-corniculatum\\\/\",\"name\":\"Glaucium corniculatum - Flores de los Caminos a Santiago\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/plant-soorten\\\/glaucium-corniculatum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/plant-soorten\\\/glaucium-corniculatum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Glaucium_corniculatum-1.jpg\",\"datePublished\":\"2021-07-15T15:01:35+00:00\",\"dateModified\":\"2026-04-23T12:37:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/plant-soorten\\\/glaucium-corniculatum\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/plant-soorten\\\/glaucium-corniculatum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/plant-soorten\\\/glaucium-corniculatum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Glaucium_corniculatum-1.jpg\",\"contentUrl\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Glaucium_corniculatum-1.jpg\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/plant-soorten\\\/glaucium-corniculatum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plant species\",\"item\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/plant-soorten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Glaucium corniculatum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/\",\"name\":\"Flores de los Caminos a Santiago\",\"description\":\"Stimulate the interest in the flora of Spain and Portugal\",\"alternateName\":\"Stimulate the interest in the flora of Spain and Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/floresdeloscaminosasantiago.eu\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Glaucium corniculatum - Flores de los Caminos a Santiago","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/","og_locale":"nl_NL","og_type":"article","og_title":"Glaucium corniculatum - Flores de los Caminos a Santiago","og_url":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/","og_site_name":"Flores de los Caminos a Santiago","article_modified_time":"2026-04-23T12:37:07+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Glaucium_corniculatum-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/","url":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/","name":"Glaucium corniculatum - Flores de los Caminos a Santiago","isPartOf":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/#primaryimage"},"image":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/#primaryimage"},"thumbnailUrl":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Glaucium_corniculatum-1.jpg","datePublished":"2021-07-15T15:01:35+00:00","dateModified":"2026-04-23T12:37:07+00:00","breadcrumb":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/#primaryimage","url":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Glaucium_corniculatum-1.jpg","contentUrl":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Glaucium_corniculatum-1.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/glaucium-corniculatum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/"},{"@type":"ListItem","position":2,"name":"Plant species","item":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/plant-soorten\/"},{"@type":"ListItem","position":3,"name":"Glaucium corniculatum"}]},{"@type":"WebSite","@id":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/#website","url":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/","name":"Flores de los Caminos a Santiago","description":"Stimulate the interest in the flora of Spain and Portugal","alternateName":"Stimulate the interest in the flora of Spain and Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/plant-species\/60688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/plant-species"}],"about":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/types\/plant-species"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/media\/37274"}],"wp:attachment":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/media?parent=60688"}],"wp:term":[{"taxonomy":"families","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/families?post=60688"},{"taxonomy":"ecologie","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/ecologie?post=60688"},{"taxonomy":"flowering-months","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/flowering-months?post=60688"},{"taxonomy":"plant-sizes","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/plant-sizes?post=60688"},{"taxonomy":"flower-sizes","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/flower-sizes?post=60688"},{"taxonomy":"provinces","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/provinces?post=60688"},{"taxonomy":"caminos","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/caminos?post=60688"},{"taxonomy":"colors","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/colors?post=60688"},{"taxonomy":"countries","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/nl\/wp-json\/wp\/v2\/countries?post=60688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}