{"id":59993,"date":"2021-07-15T17:02:38","date_gmt":"2021-07-15T15:02:38","guid":{"rendered":"https:\/\/floresdeloscaminosasantiago.eu\/plant-species\/prunella-grandiflora\/"},"modified":"2026-04-23T14:34:52","modified_gmt":"2026-04-23T12:34:52","slug":"prunella-grandiflora","status":"publish","type":"plant-species","link":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/","title":{"rendered":"Prunella grandiflora"},"featured_media":41671,"parent":0,"template":"","meta":[],"families":[7106],"ecologie":[6247,7107],"flowering-months":[9621],"plant-sizes":[9740],"flower-sizes":[10684],"provinces":[11206],"caminos":[4633],"colors":[5905,5889],"countries":[1123],"class_list":["post-59993","plant-species","type-plant-species","status-publish","has-post-thumbnail","hentry","families-prunella-es","ecologie-grasslands-es","ecologie-humid-fresh-slopes-in-woods-or-scrub-es","flowering-months-6-9-es","plant-sizes-1-3-dm-es","flower-sizes-25-30-mm-es","provinces-alava-es","caminos-camino-vasco-del-interior","colors-azul","colors-morado","countries-spain"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prunella grandiflora - Flores de los Caminos a Santiago<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prunella grandiflora - Flores de los Caminos a Santiago\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/\" \/>\n<meta property=\"og:site_name\" content=\"Flores de los Caminos a Santiago\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T12:34:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Prunella_grandiflora-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/\",\"url\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/\",\"name\":\"Prunella grandiflora - Flores de los Caminos a Santiago\",\"isPartOf\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Prunella_grandiflora-1.jpg\",\"datePublished\":\"2021-07-15T15:02:38+00:00\",\"dateModified\":\"2026-04-23T12:34:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#primaryimage\",\"url\":\"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Prunella_grandiflora-1.jpg\",\"contentUrl\":\"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Prunella_grandiflora-1.jpg\",\"width\":600,\"height\":567},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plant species\",\"item\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prunella grandiflora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/#website\",\"url\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/\",\"name\":\"Flores de los Caminos a Santiago\",\"description\":\"Stimulate the interest in the flora of Spain and Portugal\",\"alternateName\":\"Stimulate the interest in the flora of Spain and Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prunella grandiflora - Flores de los Caminos a Santiago","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/","og_locale":"es_ES","og_type":"article","og_title":"Prunella grandiflora - Flores de los Caminos a Santiago","og_url":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/","og_site_name":"Flores de los Caminos a Santiago","article_modified_time":"2026-04-23T12:34:52+00:00","og_image":[{"width":600,"height":567,"url":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Prunella_grandiflora-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/","url":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/","name":"Prunella grandiflora - Flores de los Caminos a Santiago","isPartOf":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#primaryimage"},"image":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#primaryimage"},"thumbnailUrl":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Prunella_grandiflora-1.jpg","datePublished":"2021-07-15T15:02:38+00:00","dateModified":"2026-04-23T12:34:52+00:00","breadcrumb":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#primaryimage","url":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Prunella_grandiflora-1.jpg","contentUrl":"https:\/\/floresdeloscaminosasantiago.eu\/wp-content\/uploads\/2022\/01\/Prunella_grandiflora-1.jpg","width":600,"height":567},{"@type":"BreadcrumbList","@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/prunella-grandiflora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/floresdeloscaminosasantiago.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Plant species","item":"https:\/\/floresdeloscaminosasantiago.eu\/es\/especies-de-plantas\/"},{"@type":"ListItem","position":3,"name":"Prunella grandiflora"}]},{"@type":"WebSite","@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/#website","url":"https:\/\/floresdeloscaminosasantiago.eu\/es\/","name":"Flores de los Caminos a Santiago","description":"Stimulate the interest in the flora of Spain and Portugal","alternateName":"Stimulate the interest in the flora of Spain and Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floresdeloscaminosasantiago.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/plant-species\/59993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/plant-species"}],"about":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/types\/plant-species"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/media\/41671"}],"wp:attachment":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/media?parent=59993"}],"wp:term":[{"taxonomy":"families","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/families?post=59993"},{"taxonomy":"ecologie","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/ecologie?post=59993"},{"taxonomy":"flowering-months","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/flowering-months?post=59993"},{"taxonomy":"plant-sizes","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/plant-sizes?post=59993"},{"taxonomy":"flower-sizes","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/flower-sizes?post=59993"},{"taxonomy":"provinces","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/provinces?post=59993"},{"taxonomy":"caminos","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/caminos?post=59993"},{"taxonomy":"colors","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/colors?post=59993"},{"taxonomy":"countries","embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/countries?post=59993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}