{"id":7129,"count":11,"description":"","link":"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/","name":"Plantago","slug":"plantago-es","taxonomy":"families","parent":9563,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plantago - Flores de los Caminos a Santiago<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plantago - Flores de los Caminos a Santiago\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Flores de los Caminos a Santiago\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/\",\"url\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/\",\"name\":\"Plantago - Flores de los Caminos a Santiago\",\"isPartOf\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dicotyledonae\",\"item\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plantaginaceae\",\"item\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Plantago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/#website\",\"url\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/\",\"name\":\"Flores de los Caminos a Santiago\",\"description\":\"Stimulate the interest in the flora of Spain and Portugal\",\"alternateName\":\"Stimulate the interest in the flora of Spain and Portugal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/floresdeloscaminosasantiago.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plantago - Flores de los Caminos a Santiago","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/","og_locale":"es_ES","og_type":"article","og_title":"Plantago - Flores de los Caminos a Santiago","og_url":"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/","og_site_name":"Flores de los Caminos a Santiago","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/","url":"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/","name":"Plantago - Flores de los Caminos a Santiago","isPartOf":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/#website"},"breadcrumb":{"@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/plantago-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/floresdeloscaminosasantiago.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Dicotyledonae","item":"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/"},{"@type":"ListItem","position":3,"name":"Plantaginaceae","item":"https:\/\/floresdeloscaminosasantiago.eu\/es\/families\/dicotyledonae-es\/plantaginaceae-es\/"},{"@type":"ListItem","position":4,"name":"Plantago"}]},{"@type":"WebSite","@id":"https:\/\/floresdeloscaminosasantiago.eu\/es\/#website","url":"https:\/\/floresdeloscaminosasantiago.eu\/es\/","name":"Flores de los Caminos a Santiago","description":"Stimulate the interest in the flora of Spain and Portugal","alternateName":"Stimulate the interest in the flora of Spain and Portugal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floresdeloscaminosasantiago.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/families\/7129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/families"}],"about":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/taxonomies\/families"}],"up":[{"embeddable":true,"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/families\/9563"}],"wp:post_type":[{"href":"https:\/\/floresdeloscaminosasantiago.eu\/es\/wp-json\/wp\/v2\/plant-species?families=7129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}